{"id":1957,"count":1,"description":"","link":"https:\/\/vuz.osvita.net\/en\/tag\/peremozhtsi\/","name":"The winners","slug":"peremozhtsi","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u041f\u0435\u0440\u0435\u043c\u043e\u0436\u0446\u0456 - \u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vuz.osvita.net\/en\/tag\/peremozhtsi\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041f\u0435\u0440\u0435\u043c\u043e\u0436\u0446\u0456 - \u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vuz.osvita.net\/en\/tag\/peremozhtsi\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/vuz.osvita.net\\\/tag\\\/peremozhtsi\\\/\",\"url\":\"https:\\\/\\\/vuz.osvita.net\\\/tag\\\/peremozhtsi\\\/\",\"name\":\"\u041f\u0435\u0440\u0435\u043c\u043e\u0436\u0446\u0456 - \u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vuz.osvita.net\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vuz.osvita.net\\\/tag\\\/peremozhtsi\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vuz.osvita.net\\\/tag\\\/peremozhtsi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/vuz.osvita.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041f\u0435\u0440\u0435\u043c\u043e\u0436\u0446\u0456\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vuz.osvita.net\\\/#website\",\"url\":\"https:\\\/\\\/vuz.osvita.net\\\/\",\"name\":\"\u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb\",\"description\":\"\u0415\u0444\u0435\u043a\u0442\u0438\u0432\u043d\u0435 \u0443\u043f\u0440\u0430\u0432\u043b\u0456\u043d\u043d\u044f \u0417\u0412\u041e\",\"publisher\":{\"@id\":\"https:\\\/\\\/vuz.osvita.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vuz.osvita.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vuz.osvita.net\\\/#organization\",\"name\":\"\u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb\",\"url\":\"https:\\\/\\\/vuz.osvita.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vuz.osvita.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vuz.osvita.net\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo_big-1024x1024-1.png\",\"contentUrl\":\"https:\\\/\\\/vuz.osvita.net\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo_big-1024x1024-1.png\",\"width\":1024,\"height\":1024,\"caption\":\"\u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb\"},\"image\":{\"@id\":\"https:\\\/\\\/vuz.osvita.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ndipit.com.ua\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041f\u0435\u0440\u0435\u043c\u043e\u0436\u0446\u0456 - \u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vuz.osvita.net\/en\/tag\/peremozhtsi\/","og_locale":"en_GB","og_type":"article","og_title":"\u041f\u0435\u0440\u0435\u043c\u043e\u0436\u0446\u0456 - \u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb","og_url":"https:\/\/vuz.osvita.net\/en\/tag\/peremozhtsi\/","og_site_name":"\u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/vuz.osvita.net\/tag\/peremozhtsi\/","url":"https:\/\/vuz.osvita.net\/tag\/peremozhtsi\/","name":"The winners are ASU \"VNZ\"","isPartOf":{"@id":"https:\/\/vuz.osvita.net\/#website"},"breadcrumb":{"@id":"https:\/\/vuz.osvita.net\/tag\/peremozhtsi\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/vuz.osvita.net\/tag\/peremozhtsi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/vuz.osvita.net\/"},{"@type":"ListItem","position":2,"name":"\u041f\u0435\u0440\u0435\u043c\u043e\u0436\u0446\u0456"}]},{"@type":"WebSite","@id":"https:\/\/vuz.osvita.net\/#website","url":"https:\/\/vuz.osvita.net\/","name":"ASU \u00abVNZ\u00bb","description":"Effective management of higher education institutions","publisher":{"@id":"https:\/\/vuz.osvita.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vuz.osvita.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/vuz.osvita.net\/#organization","name":"ASU \u00abVNZ\u00bb","url":"https:\/\/vuz.osvita.net\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vuz.osvita.net\/#\/schema\/logo\/image\/","url":"https:\/\/vuz.osvita.net\/wp-content\/uploads\/2022\/12\/logo_big-1024x1024-1.png","contentUrl":"https:\/\/vuz.osvita.net\/wp-content\/uploads\/2022\/12\/logo_big-1024x1024-1.png","width":1024,"height":1024,"caption":"\u0410\u0421\u0423 \u00ab\u0412\u041d\u0417\u00bb"},"image":{"@id":"https:\/\/vuz.osvita.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ndipit.com.ua"]}]}},"_links":{"self":[{"href":"https:\/\/vuz.osvita.net\/en\/wp-json\/wp\/v2\/tags\/1957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vuz.osvita.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/vuz.osvita.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/vuz.osvita.net\/en\/wp-json\/wp\/v2\/posts?tags=1957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}